{"id":11,"date":"2017-06-25T08:43:09","date_gmt":"2017-06-25T08:43:09","guid":{"rendered":"http:\/\/aktihotel.tp-server.gr\/?page_id=11"},"modified":"2019-01-29T14:12:02","modified_gmt":"2019-01-29T12:12:02","slug":"welcome-to-akti-hotel-at-molyvos-lesvos-greece","status":"publish","type":"page","link":"https:\/\/www.akti-hotel-molyvos.com\/de\/","title":{"rendered":"Willkommen im Akti Hotel in Molyvos Lesvos Griechenland"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">AKTI HOTEL &#8211; MOLYVOS<\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-164 size-full\" src=\"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-content\/uploads\/2017\/06\/banner1.jpg\" alt=\"\" width=\"375\" height=\"180\" srcset=\"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-content\/uploads\/2017\/06\/banner1.jpg 375w, https:\/\/www.akti-hotel-molyvos.com\/de\/wp-content\/uploads\/2017\/06\/banner1-300x144.jpg 300w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D22|||&#8221; css=&#8221;.vc_custom_1499444185020{margin-top: -30px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">UNTERKUNFT<\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-173 size-full\" src=\"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-content\/uploads\/2017\/06\/banner2.jpg\" alt=\"\" width=\"375\" height=\"180\" \/><\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D64|||&#8221; css=&#8221;.vc_custom_1499444190025{margin-top: -30px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<h3 style=\"text-align: center;\">MYTHIMNA &#8211; MOLYVOS<\/h3>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-175 size-full\" src=\"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-content\/uploads\/2017\/06\/banner3.jpg\" alt=\"\" width=\"375\" height=\"180\" \/><\/p>\n<p>[\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D99|||&#8221; css=&#8221;.vc_custom_1499444194731{margin-top: -30px !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/3&#8243;][vc_column_text] AKTI HOTEL &#8211; MOLYVOS [\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D22|||&#8221; css=&#8221;.vc_custom_1499444185020{margin-top: -30px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text] UNTERKUNFT [\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D64|||&#8221; css=&#8221;.vc_custom_1499444190025{margin-top: -30px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text] MYTHIMNA &#8211; MOLYVOS [\/vc_column_text][vc_btn title=&#8221;Mehr&#8230;&#8221; style=&#8221;gradient&#8221; gradient_color_1=&#8221;sky&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; button_block=&#8221;true&#8221; link=&#8221;url:https%3A%2F%2Fwww.akti-hotel-molyvos.com%2Fde%2F%3Fpage_id%3D99|||&#8221; css=&#8221;.vc_custom_1499444194731{margin-top: -30px !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":9,"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":184,"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/pages\/11\/revisions\/184"}],"wp:attachment":[{"href":"https:\/\/www.akti-hotel-molyvos.com\/de\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}